{"id":3417,"date":"2023-07-03T10:03:15","date_gmt":"2023-07-03T08:03:15","guid":{"rendered":"https:\/\/parr78.fr\/Wpress\/?p=3417"},"modified":"2023-07-03T15:57:26","modified_gmt":"2023-07-03T13:57:26","slug":"au-revoir-le-vox-bonjour-le-cineparadis","status":"publish","type":"post","link":"https:\/\/parr78.fr\/Wpress\/au-revoir-le-vox-bonjour-le-cineparadis\/","title":{"rendered":"Au revoir le VOX, bonjour le Cin\u00e9paradis."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3417\" class=\"elementor elementor-3417\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c7f04c8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c7f04c8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-70acaa3b\" data-id=\"70acaa3b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cc14486 elementor-widget elementor-widget-text-editor\" data-id=\"2cc14486\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p>En novembre 2019, nous avons pu assister \u00e0 la derni\u00e8re projection dans notre cin\u00e9ma VOX. Apr\u00e8s des ann\u00e9es de r\u00e9flexion et d\u2019\u00e9changes avec diff\u00e9rents partenaires, la ville de Rambouillet annon\u00e7ait alors le lancement d\u2019un grand projet de construction d\u2019un nouvel ensemble plus moderne et plus vaste sur des terrains qu\u2019elle avait acquis peu \u00e0 peu pour \u00e9largir l\u2019emprise duc VOX.<\/p>\n\n\n\n<p>PARR a tenu \u00e0 suivre d\u00e9s le d\u00e9but ce projet qui constitue, avec la Lanterne, un am\u00e9nagement majeur du centre-ville. Nous avons ainsi publi\u00e9 sur notre site, pendant la difficile p\u00e9riode des confinements successifs n\u00e9cessit\u00e9s par l\u2019\u00e9pid\u00e9mie de COVID, trois articles permettant de suivre son histoire et de comprendre ce que devenait notre cin\u00e9ma.<\/p>\n\n\n\n<p>&#8211; 15 f\u00e9vrier 2020: pr\u00e9sentation du projet<\/p>\n\n\n\n<p>&#8211; 9 mai 2020: le diagnostic arch\u00e9ologique<\/p>\n\n\n\n<p>&#8211; 24 f\u00e9vrier 2021: la fin du VOX<\/p>\n\n\n\n<p>En ce d\u00e9but de 2021, nous apprenions malheureusement que le partenaire qui avait sign\u00e9 une convention avec la Ville comprenant la construction du nouveau cin\u00e9ma et son exploitation \u00e9tait amen\u00e9 \u00e0 renoncer \u00e0 ce projet compte tenu de l\u2019\u00e9volution de la situation \u00e9conomique. Depuis nous n\u2019avions plus qu\u2019\u00e0 contempler le champ de ruines qu\u2019\u00e9tait devenu notre cin\u00e9ma et d\u00e9plorer dans nos chroniques, notamment lors des assembl\u00e9es g\u00e9n\u00e9rales de PARR, l\u2019absence de cette offre culturelle au sein de notre ville.<\/p>\n\n\n\n<p>Une premi\u00e8re r\u00e9ponse fut l\u2019am\u00e9nagement de la salle Monique le Dilly \u00e0 la Lanterne et le contrat provisoire sign\u00e9 avec la soci\u00e9t\u00e9 Megarama permettant de projeter des films plusieurs fois par semaine. Mais c\u2019\u00e9tait \u00e0 l\u2019\u00e9vidence une solution temporaire et insuffisante. Nous esp\u00e9rions que la Municipalit\u00e9 avait bien pris ce dossier \u00e0 coeur et continuait de chercher, dans la confidentialit\u00e9 indispensable dans ce milieu du cin\u00e9ma, de nouveaux partenaires.<\/p>\n\n\n\n<p>C\u2019est avec le plus grand plaisir que nous avons appris que le conseil municipal du 29 juin avait \u00e9t\u00e9 inform\u00e9 que les n\u00e9gociations avaient abouti et avait adopt\u00e9, \u00e0 l\u2019unanimit\u00e9 la cession du contrat \u00e0 un nouveau partenaire Rencontr\u00e9e le lendemain, Madame le Maire, V\u00e9ronique Matillon nous a confirm\u00e9 la bonne nouvelle et nous a dit \u00e0 quel point elle \u00e9tait heureuse qu\u2019une solution soit enfin trouv\u00e9e.<\/p>\n\n\n\n<p>Non seulement, la solution a \u00e9t\u00e9 trouv\u00e9e mais elle r\u00e9pond \u00e0 toutes les attentes que l\u2019on pouvait formuler. La soci\u00e9t\u00e9 L\u2019Ermitage, dirig\u00e9e par Judith Reynaud rach\u00e8te en effet la soci\u00e9t\u00e9 du pr\u00e9c\u00e9dent titulaire, reprenant ainsi \u00a0l\u2019ensemble du projet tel qu\u2019il avait \u00e9t\u00e9 d\u00e9fini initialement. M\u00eame architecture, m\u00eame philosophie de l\u2019exploitation, m\u00eames conditions d\u00e9 r\u00e9alisation. Pour ceux qui\u00a0 ont peut-\u00eatre eu l\u2019occasion de se rendre \u00e0 Chartres pendant cette p\u00e9riode de disette cin\u00e9matographique, ils connaissent bien cette entreprise puisque elle y g\u00e8re le cin\u00e9ma \u00ab\u00a0les enfants du paradis\u00a0\u00bb. Sa responsable poss\u00e8de aussi sous le m\u00eame vocable les deux cin\u00e9mas de Fontainebleau et celui de Nemours. Il s\u2019agit donc bien d\u2019un partenaire solide et exp\u00e9riment\u00e9. Le projet d\u2019un montant total de 5,8 millions, sera soutenu comme le pr\u00e9c\u00e9dent par des subventions venant de la Ville, du D\u00e9partement et la R\u00e9gion.<\/p>\n\n\n\n<p>Notre nouveau cin\u00e9ma sera \u00e9videmment dot\u00e9 des derni\u00e8res technologies, madame Reynaud tenant tout particuli\u00e8rement \u00e0 am\u00e9liorer en permanence son offre. Il proposera dans 5 salles des films 7\/7 jours et sur 365 jours. Il conservera sa vocation de cin\u00e9ma d\u2019art et d\u2019essai et une salle pourra accueillir des manifestations exceptionnelles ainsi que des activit\u00e9s associatives.<\/p>\n\n\n\n<p>Bien s\u00fbr nous devons encore \u00eatre patients car sa r\u00e9alisation va demander du temps m\u00eame si le fait de prendre le m\u00eame projet et le m\u00eame architecte permet de commencer assez rapidement les travaux. En \u00e9tant raisonnablement optimistes, on peut esp\u00e9rer acheter nos premiers billets au printemps 2025.<\/p>\n\n\n\n<p>Son nom, le Cin\u00e9paradis, est en lui-m\u00eame une appellation pleine de belles promesses.<\/p>\n\n\n\n<p><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En novembre 2019, nous avons pu assister \u00e0 la derni\u00e8re projection dans notre cin\u00e9ma VOX. Apr\u00e8s des ann\u00e9es de r\u00e9flexion et d\u2019\u00e9changes avec diff\u00e9rents partenaires, la ville de Rambouillet annon\u00e7ait alors le lancement d\u2019un grand projet de construction d\u2019un nouvel ensemble plus moderne et plus vaste sur des terrains qu\u2019elle avait acquis peu \u00e0 peu [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[6,20],"tags":[],"class_list":["post-3417","post","type-post","status-publish","format-standard","hentry","category-etudes","category-actualites","entry"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Ren\u00e9 Fisher","author_link":"https:\/\/parr78.fr\/Wpress\/author\/rene\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/parr78.fr\/Wpress\/category\/etudes\/\" rel=\"category tag\">3 - Dossiers\/Etudes<\/a> <a href=\"https:\/\/parr78.fr\/Wpress\/category\/actualites\/\" rel=\"category tag\">Actualit\u00e9s<\/a>","rttpg_excerpt":"En novembre 2019, nous avons pu assister \u00e0 la derni\u00e8re projection dans notre cin\u00e9ma VOX. Apr\u00e8s des ann\u00e9es de r\u00e9flexion et d\u2019\u00e9changes avec diff\u00e9rents partenaires, la ville de Rambouillet annon\u00e7ait alors le lancement d\u2019un grand projet de construction d\u2019un nouvel ensemble plus moderne et plus vaste sur des terrains qu\u2019elle avait acquis peu \u00e0 peu\u2026","_links":{"self":[{"href":"https:\/\/parr78.fr\/Wpress\/wp-json\/wp\/v2\/posts\/3417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/parr78.fr\/Wpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/parr78.fr\/Wpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/parr78.fr\/Wpress\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/parr78.fr\/Wpress\/wp-json\/wp\/v2\/comments?post=3417"}],"version-history":[{"count":5,"href":"https:\/\/parr78.fr\/Wpress\/wp-json\/wp\/v2\/posts\/3417\/revisions"}],"predecessor-version":[{"id":3452,"href":"https:\/\/parr78.fr\/Wpress\/wp-json\/wp\/v2\/posts\/3417\/revisions\/3452"}],"wp:attachment":[{"href":"https:\/\/parr78.fr\/Wpress\/wp-json\/wp\/v2\/media?parent=3417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/parr78.fr\/Wpress\/wp-json\/wp\/v2\/categories?post=3417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/parr78.fr\/Wpress\/wp-json\/wp\/v2\/tags?post=3417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}